{"id":262,"date":"2025-06-05T12:36:41","date_gmt":"2025-06-05T12:36:41","guid":{"rendered":"https:\/\/mostesidolomitesspahotel.com\/?page_id=262"},"modified":"2025-07-28T14:27:48","modified_gmt":"2025-07-28T14:27:48","slug":"mostesi-dolomites-spa-hotel-gusto","status":"publish","type":"page","link":"https:\/\/mostesidolomitesspahotel.com\/it\/mostesi-dolomites-spa-hotel-gusto\/","title":{"rendered":"Mostesi Dolomites Spa Hotel &#8211; Gusto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"262\" class=\"elementor elementor-262\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adfe9a1 e-con-full e-flex e-con e-parent\" data-id=\"adfe9a1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vimeo.com\\\/1105148043&quot;,&quot;background_video_end&quot;:63,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-6d54b26 elementor-widget elementor-widget-image\" data-id=\"6d54b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"395\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-1024x505.png\" class=\"attachment-large size-large wp-image-28\" alt=\"\" srcset=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-1024x505.png 1024w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-300x148.png 300w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-768x379.png 768w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-1536x758.png 1536w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/01\/MOstesi-Full-Logo-White-2048x1010.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fe0c29 e-flex e-con-boxed e-con e-parent\" data-id=\"1fe0c29\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-976e155 e-con-full e-flex e-con e-child\" data-id=\"976e155\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60fb29d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"60fb29d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Colazione Artigianale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b441b elementor-widget elementor-widget-text-editor\" data-id=\"29b441b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p class=\"p1\"><span style=\"font-weight: 400;\">Ogni giornata al Mostesi inizia con un rituale lento, fatto di profumi che accolgono ancor prima di aprire gli occhi. Al centro di questo risveglio, c\u2019\u00e8 il lavoro sapiente del nostro maestro pasticcere Stefano: mani esperte che ogni mattina impastano, sfornano e decorano. Ogni dolce \u00e8 preparato in casa, ogni torta nasce da ricette custodite e interpretate con cura. Crostate friabili, lievitati morbidi, biscotti fragranti \u2014 tutto parla di attenzione, stagionalit\u00e0, rispetto per la materia prima.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f848e2 e-con-full e-flex e-con e-child\" data-id=\"1f848e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e96b80 elementor-widget elementor-widget-image\" data-id=\"5e96b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-683x1024.jpg\" class=\"attachment-large size-large wp-image-404\" alt=\"\" srcset=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-683x1024.jpg 683w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-200x300.jpg 200w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-768x1152.jpg 768w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-1024x1536.jpg 1024w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28-8x12.jpg 8w, https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-28.jpg 1280w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b53f1bd e-flex e-con-boxed e-con e-parent\" data-id=\"b53f1bd\" data-element_type=\"container\" data-e-type=\"container\" id=\"camere\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6053352 e-con-full e-flex e-con e-child\" data-id=\"6053352\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfc9154 elementor-widget elementor-widget-text-editor\" data-id=\"cfc9154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p><span style=\"font-weight: 400;\">Accanto alla parte dolce, non manca una selezione di proposte salate: pane caldo, formaggi d\u2019alpeggio dal taglio deciso, uova freschissime cucinate al momento, verdure locali, burro di malga, affettati scelti con rigore. Ogni elemento viene selezionato da realt\u00e0 agricole del territorio, per portare in tavola non solo qualit\u00e0 ma anche appartenenza.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1bbd9a e-con-full e-flex e-con e-child\" data-id=\"d1bbd9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3964f03 elementor-widget elementor-widget-text-editor\" data-id=\"3964f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">Scorri le immagini \u2192 Clicca per ingrandire<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f81eda4 elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"f81eda4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f81eda4\" data-elementor-lightbox-title=\"mostesi_colazione_web-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwLCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0xLmpwZyIsInNsaWRlc2hvdyI6ImY4MWVkYTQifQ%3D%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-1.jpg\" alt=\"mostesi_colazione_web-1\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f81eda4\" data-elementor-lightbox-title=\"mostesi_colazione_web-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDAyLCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0zLmpwZyIsInNsaWRlc2hvdyI6ImY4MWVkYTQifQ%3D%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-3.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-3.jpg\" alt=\"mostesi_colazione_web-3\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f81eda4\" data-elementor-lightbox-title=\"mostesi_colazione_web-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDAzLCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0yLmpwZyIsInNsaWRlc2hvdyI6ImY4MWVkYTQifQ%3D%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-2.jpg\" alt=\"mostesi_colazione_web-2\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-302db9b e-flex e-con-boxed e-con e-parent\" data-id=\"302db9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8f4f1ac e-con-full e-flex e-con e-child\" data-id=\"8f4f1ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8c69c6 elementor-widget elementor-widget-text-editor\" data-id=\"d8c69c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p><span style=\"font-weight: 400;\">La sala colazioni si riempie di luce e piccoli gesti: una moka che borbotta in sottofondo, un vassoio che arriva caldo, uno sguardo che sorride. \u00c8 una colazione che non ha fretta, che nutre e racconta. Una colazione che, prima ancora di uscire, ti fa sentire gi\u00e0 nel cuore delle Dolomiti.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d0b6b8 e-con-full e-flex e-con e-child\" data-id=\"3d0b6b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93a230c elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"93a230c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.simplebooking.it\/ibe2\/hotel\/10279\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-check\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 64h-48V12c0-6.627-5.373-12-12-12h-40c-6.627 0-12 5.373-12 12v52H160V12c0-6.627-5.373-12-12-12h-40c-6.627 0-12 5.373-12 12v52H48C21.49 64 0 85.49 0 112v352c0 26.51 21.49 48 48 48h352c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm-6 400H54a6 6 0 0 1-6-6V160h352v298a6 6 0 0 1-6 6zm-52.849-200.65L198.842 404.519c-4.705 4.667-12.303 4.637-16.971-.068l-75.091-75.699c-4.667-4.705-4.637-12.303.068-16.971l22.719-22.536c4.705-4.667 12.303-4.637 16.97.069l44.104 44.461 111.072-110.181c4.705-4.667 12.303-4.637 16.971.068l22.536 22.718c4.667 4.705 4.636 12.303-.069 16.97z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prenota<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b872622 elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"b872622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi Info<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20f82ec e-con-full e-flex e-con e-child\" data-id=\"20f82ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-459bf96 elementor-widget elementor-widget-text-editor\" data-id=\"459bf96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">Scorri le immagini \u2192 Clicca per ingrandire<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9361f elementor-widget__width-initial elementor-widget elementor-widget-image-carousel\" data-id=\"9e9361f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9e9361f\" data-elementor-lightbox-title=\"mostesi_colazione_web-29\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg1LCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0yOS5qcGciLCJzbGlkZXNob3ciOiI5ZTkzNjFmIn0%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-29.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-29.jpg\" alt=\"mostesi_colazione_web-29\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9e9361f\" data-elementor-lightbox-title=\"mostesi_colazione_web-23\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg2LCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0yMy5qcGciLCJzbGlkZXNob3ciOiI5ZTkzNjFmIn0%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-23.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-23.jpg\" alt=\"mostesi_colazione_web-23\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9e9361f\" data-elementor-lightbox-title=\"mostesi_colazione_web-8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg5LCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi04LmpwZyIsInNsaWRlc2hvdyI6IjllOTM2MWYifQ%3D%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-8.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-8.jpg\" alt=\"mostesi_colazione_web-8\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9e9361f\" data-elementor-lightbox-title=\"mostesi_colazione_web-22\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3LCJ1cmwiOiJodHRwczpcL1wvbW9zdGVzaWRvbG9taXRlc3NwYWhvdGVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL21vc3Rlc2lfY29sYXppb25lX3dlYi0yMi5qcGciLCJzbGlkZXNob3ciOiI5ZTkzNjFmIn0%3D\" href=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-22.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mostesidolomitesspahotel.com\/wp-content\/uploads\/2025\/06\/mostesi_colazione_web-22.jpg\" alt=\"mostesi_colazione_web-22\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8699407 e-con-full e-flex e-con e-parent\" data-id=\"8699407\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-df9be38 e-con-full e-flex e-con e-child\" data-id=\"df9be38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc49887 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"bc49887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Non solo gusto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f388f75 elementor-widget elementor-widget-text-editor\" data-id=\"f388f75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"43dd34d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div>Scopri tutti i servizi offerti e vivi un&#8217;esperienza indimenticabile tra le meravigliose Dolomiti.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a162e7 e-con-full e-flex e-con e-child\" data-id=\"4a162e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a49e66 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8a49e66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Camere<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e815ca5 elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"e815ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mostesidolomitesspahotel.com\/mostesi-dolomites-spa-hotel-camere\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d842ed7 e-con-full e-flex e-con e-child\" data-id=\"d842ed7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54cbfec elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"54cbfec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experience<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d65060b elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"d65060b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mostesidolomitesspahotel.com\/mostesi-dolomites-spa-hotel-experience\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c12e668 e-con-full e-flex e-con e-child\" data-id=\"c12e668\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e13e2d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7e13e2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9521045 elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"9521045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mostesidolomitesspahotel.com\/mostesi-dolomites-spa-hotel-wellness-auronzo-di-cadore\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Colazione Artigianale Ogni giornata al Mostesi inizia con un rituale lento, fatto di profumi che accolgono ancor prima di aprire gli occhi. Al centro di questo risveglio, c\u2019\u00e8 il lavoro sapiente del nostro maestro pasticcere Stefano: mani esperte che ogni mattina impastano, sfornano e decorano. Ogni dolce \u00e8 preparato in casa, ogni torta nasce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-262","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/pages\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":21,"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/pages\/262\/revisions"}],"predecessor-version":[{"id":461,"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/pages\/262\/revisions\/461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/media\/130"}],"wp:attachment":[{"href":"https:\/\/mostesidolomitesspahotel.com\/it\/wp-json\/wp\/v2\/media?parent=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}